{"id":1106,"date":"2020-08-13T11:24:44","date_gmt":"2020-08-13T11:24:44","guid":{"rendered":"http:\/\/fullcrazylife.com\/root\/?page_id=1106"},"modified":"2020-08-13T11:24:44","modified_gmt":"2020-08-13T11:24:44","slug":"bloggin-it-up","status":"publish","type":"page","link":"http:\/\/fullcrazylife.com\/root\/bloggin-it-up\/","title":{"rendered":"Bloggin it up."},"content":{"rendered":"<ul class=\"wp-block-latest-posts__list wp-block-latest-posts\"><li><a class=\"wp-block-latest-posts__post-title\" href=\"http:\/\/fullcrazylife.com\/root\/2020\/08\/15\/usb-rechargeable-plasma-lighters\/\">USB Rechargeable plasma lighters<\/a><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"http:\/\/fullcrazylife.com\/root\/2020\/08\/13\/so-i-bought-a-ro\/\">So, I bought a Ro..<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1106","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bloggin it up. &#8212; It&#039;s a New Life<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/fullcrazylife.com\/root\/bloggin-it-up\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bloggin it up. &#8212; It&#039;s a New Life\" \/>\n<meta property=\"og:url\" content=\"http:\/\/fullcrazylife.com\/root\/bloggin-it-up\/\" \/>\n<meta property=\"og:site_name\" content=\"It&#039;s a New Life\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FullCrazyLifecom-114843505246383\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Fullcrazylife\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/fullcrazylife.com\\\/root\\\/bloggin-it-up\\\/\",\"url\":\"http:\\\/\\\/fullcrazylife.com\\\/root\\\/bloggin-it-up\\\/\",\"name\":\"Bloggin it up. &#8212; It&#039;s a New Life\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/fullcrazylife.com\\\/root\\\/#website\"},\"datePublished\":\"2020-08-13T11:24:44+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/fullcrazylife.com\\\/root\\\/bloggin-it-up\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/fullcrazylife.com\\\/root\\\/bloggin-it-up\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/fullcrazylife.com\\\/root\\\/bloggin-it-up\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/fullcrazylife.com\\\/root\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bloggin it up.\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/fullcrazylife.com\\\/root\\\/#website\",\"url\":\"http:\\\/\\\/fullcrazylife.com\\\/root\\\/\",\"name\":\"It's a New Life\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/fullcrazylife.com\\\/root\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/fullcrazylife.com\\\/root\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/fullcrazylife.com\\\/root\\\/#organization\",\"name\":\"FullCrazyLife.com\",\"url\":\"http:\\\/\\\/fullcrazylife.com\\\/root\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/fullcrazylife.com\\\/root\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/fullcrazylife.com\\\/root\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/fcllogo-1.png\",\"contentUrl\":\"http:\\\/\\\/fullcrazylife.com\\\/root\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/fcllogo-1.png\",\"width\":175,\"height\":63,\"caption\":\"FullCrazyLife.com\"},\"image\":{\"@id\":\"http:\\\/\\\/fullcrazylife.com\\\/root\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FullCrazyLifecom-114843505246383\\\/\",\"https:\\\/\\\/x.com\\\/Fullcrazylife\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bloggin it up. &#8212; It&#039;s a New Life","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/fullcrazylife.com\/root\/bloggin-it-up\/","og_locale":"en_US","og_type":"article","og_title":"Bloggin it up. &#8212; It&#039;s a New Life","og_url":"http:\/\/fullcrazylife.com\/root\/bloggin-it-up\/","og_site_name":"It&#039;s a New Life","article_publisher":"https:\/\/www.facebook.com\/FullCrazyLifecom-114843505246383\/","twitter_card":"summary_large_image","twitter_site":"@Fullcrazylife","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/fullcrazylife.com\/root\/bloggin-it-up\/","url":"http:\/\/fullcrazylife.com\/root\/bloggin-it-up\/","name":"Bloggin it up. &#8212; It&#039;s a New Life","isPartOf":{"@id":"http:\/\/fullcrazylife.com\/root\/#website"},"datePublished":"2020-08-13T11:24:44+00:00","breadcrumb":{"@id":"http:\/\/fullcrazylife.com\/root\/bloggin-it-up\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/fullcrazylife.com\/root\/bloggin-it-up\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/fullcrazylife.com\/root\/bloggin-it-up\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/fullcrazylife.com\/root\/"},{"@type":"ListItem","position":2,"name":"Bloggin it up."}]},{"@type":"WebSite","@id":"http:\/\/fullcrazylife.com\/root\/#website","url":"http:\/\/fullcrazylife.com\/root\/","name":"It's a New Life","description":"","publisher":{"@id":"http:\/\/fullcrazylife.com\/root\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/fullcrazylife.com\/root\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/fullcrazylife.com\/root\/#organization","name":"FullCrazyLife.com","url":"http:\/\/fullcrazylife.com\/root\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/fullcrazylife.com\/root\/#\/schema\/logo\/image\/","url":"http:\/\/fullcrazylife.com\/root\/wp-content\/uploads\/2017\/02\/fcllogo-1.png","contentUrl":"http:\/\/fullcrazylife.com\/root\/wp-content\/uploads\/2017\/02\/fcllogo-1.png","width":175,"height":63,"caption":"FullCrazyLife.com"},"image":{"@id":"http:\/\/fullcrazylife.com\/root\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FullCrazyLifecom-114843505246383\/","https:\/\/x.com\/Fullcrazylife"]}]}},"_links":{"self":[{"href":"http:\/\/fullcrazylife.com\/root\/wp-json\/wp\/v2\/pages\/1106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/fullcrazylife.com\/root\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/fullcrazylife.com\/root\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/fullcrazylife.com\/root\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/fullcrazylife.com\/root\/wp-json\/wp\/v2\/comments?post=1106"}],"version-history":[{"count":1,"href":"http:\/\/fullcrazylife.com\/root\/wp-json\/wp\/v2\/pages\/1106\/revisions"}],"predecessor-version":[{"id":1107,"href":"http:\/\/fullcrazylife.com\/root\/wp-json\/wp\/v2\/pages\/1106\/revisions\/1107"}],"wp:attachment":[{"href":"http:\/\/fullcrazylife.com\/root\/wp-json\/wp\/v2\/media?parent=1106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}